{"id":3,"date":"2021-08-25T09:34:15","date_gmt":"2021-08-25T07:34:15","guid":{"rendered":"http:\/\/www.tiensmarinecree.com\/?page_id=3"},"modified":"2022-02-14T14:51:23","modified_gmt":"2022-02-14T13:51:23","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/www.tiensmarinecree.com\/index.php\/politique-de-confidentialite\/","title":{"rendered":"Mentions l\u00e9gales"},"content":{"rendered":"\n<h2>Identification<\/h2>\n\n\n\n<p>En vertu de l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\u2019\u00c9conomie Num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site internet <a href=\"http:\/\/www.tiensmarinecree.com\">www.tiensmarinecree.com<\/a> l\u2019identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi:<\/p>\n\n\n\n<p>Propri\u00e9taire : Marine Pr\u00e9vot &#8211; Siret n\u00b0899.001.788.00012 &#8211; 18 rue des aliz\u00e9s, 31750 ESCALQUENS<\/p>\n\n\n\n<p>Responsable de la publication : Marine Pr\u00e9vot &#8211; tiensmarinecree[at]mailo.com<\/p>\n\n\n\n<p>Webmaster : Marine Pr\u00e9vot &#8211; tiensmarinecree[at]mailo.com<\/p>\n\n\n\n<p>D\u00e9l\u00e9gu\u00e9e \u00e0 la protection des donn\u00e9es : Marine Pr\u00e9vot &#8211; tiensmarinecree[at]mailo.com<\/p>\n\n\n\n<p>H\u00e9bergeur : OVH &#8211; 2 rue Kellermann, 59100 ROUBAIX &#8211; 1007<\/p>\n\n\n\n<h2><span class=\"has-inline-color has-black-color\">Conditions g\u00e9n\u00e9rales <\/span>d&#8217;utilisation du site et des services propos\u00e9s<\/h2>\n\n\n\n<p>Ce site internet est une \u0153uvre prot\u00e9g\u00e9e par les dispositions du Code de la Propri\u00e9t\u00e9 Intellectuelle et des R\u00e9glementations Internationales applicables. Aucun client ne peut r\u00e9utiliser, c\u00e9der ou exploiter pour son propre compte tout ou partie des \u00e9l\u00e9ments ou travaux du site.<\/p>\n\n\n\n<p>L\u2019utilisation du site <a href=\"http:\/\/www.tiensmarinecree.com\">www.tiensmarinecree.com<\/a> implique l\u2019acceptation pleine et enti\u00e8re des conditions g\u00e9n\u00e9rales d\u2019utilisation ci-apr\u00e8s d\u00e9crites. Ces conditions d\u2019utilisation sont susceptibles d\u2019\u00eatre modifi\u00e9es ou compl\u00e9t\u00e9es \u00e0 tout moment, les utilisateurs du site <a href=\"http:\/\/www.tiensmarinecree.com\">www.tiensmarinecree.com<\/a> sont invit\u00e9s \u00e0 les consulter r\u00e9guli\u00e8rement.<\/p>\n\n\n\n<p>Ce site internet est normalement accessible \u00e0 tout moment aux utilisateurs. Une interruption pour raison de maintenance technique peut toutefois \u00eatre d\u00e9cid\u00e9e par Marine Pr\u00e9vot qui s\u2019efforcera dans ce cas de communiquer pr\u00e9alablement aux utilisateurs les dates et heures de l\u2019intervention. <br>Le site internet <a href=\"http:\/\/www.tiensmarinecree.com\">www.tiensmarinecree.com<\/a> est mis \u00e0 jour p\u00e9riodiquement par Marine Pr\u00e9vot. Les mentions l\u00e9gales peuvent notamment \u00eatre modifi\u00e9es \u00e0 tout moment : elles s\u2019imposent n\u00e9anmoins \u00e0 l\u2019utilisateur qui est invit\u00e9 \u00e0 s\u2019y r\u00e9f\u00e9rer le plus souvent possible afin d\u2019en prendre connaissance.<\/p>\n\n\n\n<h2>Description des services fournis par le site internet<\/h2>\n\n\n\n<p>Le site internet <a href=\"http:\/\/www.tiensmarinecree.com\" target=\"_blank\" rel=\"noreferrer noopener\">www.tiensmarinecree.com<\/a>&nbsp;a pour objet d&#8217;informer sur l\u2019ensemble des activit\u00e9s de l&#8217;entreprise.<br>Marine Pr\u00e9vot s\u2019efforce de communiquer des informations aussi pr\u00e9cises que possible. Toutefois, elle ne pourra \u00eatre tenue responsable des oublis, des inexactitudes et des carences dans la mise \u00e0 jour, qu\u2019elles soient de son fait ou du fait des tiers partenaires qui lui fournissent ces informations.<\/p>\n\n\n\n<p>Toutes les informations pr\u00e9sentes sur le site <a href=\"http:\/\/www.tiensmarinecree.com\">www.tiensmarinecree.com<\/a>&nbsp;sont fournies \u00e0 titre indicatif, et restent susceptibles d\u2019\u00e9voluer. Il est \u00e0 noter que les renseignements figurant sur le site <a href=\"http:\/\/www.tiensmarinecree.com\">www.tiensmarinecree.com<\/a> ne sont pas exhaustifs et qu&#8217;ils sont donn\u00e9s sous r\u00e9serve de modifications existant depuis leur mise en ligne.<\/p>\n\n\n\n<h2>Limitations contractuelles sur les donn\u00e9es techniques<\/h2>\n\n\n\n<p>Le site Internet ne pourra \u00eatre tenu responsable de dommages mat\u00e9riels li\u00e9s \u00e0 l\u2019utilisation du site. De plus, l\u2019utilisateur du site s\u2019engage \u00e0 acc\u00e9der au site en utilisant un mat\u00e9riel r\u00e9cent, ne contenant pas de virus et avec un navigateur de derni\u00e8re g\u00e9n\u00e9ration mis-\u00e0-jour.<br>Le site <a href=\"http:\/\/www.tiensmarinecree.com\">www.tiensmarinecree.com<\/a> est h\u00e9berg\u00e9 chez un prestataire sur le territoire de l\u2019Union Europ\u00e9enne conform\u00e9ment aux dispositions du R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD&nbsp;: n\u00b0 2016-679).<\/p>\n\n\n\n<p>L\u2019h\u00e9bergeur assure une continuit\u00e9 de service permanente. Il se r\u00e9serve n\u00e9anmoins la possibilit\u00e9 d\u2019interrompre ce service \u00e0 des fins de maintenance, d\u2019am\u00e9lioration de ses infrastructures, de d\u00e9faillance de ses infrastructures ou si les Prestations et Services g\u00e9n\u00e8rent un trafic r\u00e9put\u00e9 anormal.<\/p>\n\n\n\n<p>Marine Pr\u00e9vot et l\u2019h\u00e9bergeur ne peuvent \u00eatre tenus responsables d&#8217;un dysfonctionnement du r\u00e9seau Internet, des lignes t\u00e9l\u00e9phoniques ou du mat\u00e9riel informatique et de t\u00e9l\u00e9phonie li\u00e9 notamment \u00e0 l\u2019encombrement du r\u00e9seau emp\u00eachant l\u2019acc\u00e8s au serveur.<\/p>\n\n\n\n<h2>Propri\u00e9t\u00e9 intellectuelle et contrefa\u00e7ons <\/h2>\n\n\n\n<p>Marine Pr\u00e9vot est propri\u00e9taire des droits de propri\u00e9t\u00e9 intellectuelle et d\u00e9tient les droits d\u2019usage sur tous les \u00e9l\u00e9ments accessibles sur le site internet, qu&#8217;il s&#8217;agisse des textes, images, graphismes, logos, illustrations et produits num\u00e9riques  sauf indication contraire.<\/p>\n\n\n\n<p>Toute reproduction, repr\u00e9sentation, modification, publication, adaptation de tout ou partie des \u00e9l\u00e9ments du site, quel que soit le moyen ou le proc\u00e9d\u00e9 utilis\u00e9, est interdite.<\/p>\n\n\n\n<p>Toute exploitation non autoris\u00e9e du site ou d\u2019un des \u00e9l\u00e9ments qu\u2019il contient est constitutive d\u2019une contrefa\u00e7on et sera poursuivie conform\u00e9ment aux dispositions des articles L.335-2 et suivants du Code de Propri\u00e9t\u00e9 Intellectuelle.<\/p>\n\n\n\n<h2>Gestion des donn\u00e9es personnelles collect\u00e9es<\/h2>\n\n\n\n<p>L&#8217;utilisateur du site <a rel=\"noreferrer noopener\" href=\"http:\/\/www.tiensmarinecree.com\" target=\"_blank\">www.tiensmarinecree.com<\/a> est inform\u00e9 des r\u00e9glementations applicables par la loi du 21 Juin 2014 pour la confiance dans l\u2019\u00c9conomie Num\u00e9rique, la Loi Informatique et Libert\u00e9 du 06 Ao\u00fbt 2004 ainsi que du R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD&nbsp;: n\u00b0 2016-679).<\/p>\n\n\n\n<h3>Responsable<\/h3>\n\n\n\n<p>Le responsable du traitement des Donn\u00e9es Personnelles est Marine Pr\u00e9vot, repr\u00e9sentant l\u00e9gal du site <a rel=\"noreferrer noopener\" href=\"http:\/\/www.tiensmarinecree.com\" target=\"_blank\">www.tiensmarinecree.com<\/a>. <\/p>\n\n\n\n<p>En tant que responsable du traitement des donn\u00e9es collect\u00e9es, Marine Pr\u00e9vot s&#8217;engage \u00e0 respecter les dispositions l\u00e9gales en vigueur. Ainsi, il lui appartient notamment d&#8217;informer l&#8217;utilisateur de ce site de la finalit\u00e9 des traitements de donn\u00e9es r\u00e9alis\u00e9s, de lui fournir une information compl\u00e8te sur le traitement de ses donn\u00e9es personnelles et de tenir un registre des traitements conforme \u00e0 la r\u00e9alit\u00e9. <\/p>\n\n\n\n<h3>Commentaires<\/h3>\n\n\n\n<p>Quand vous laissez un commentaire sur notre site web, les donn\u00e9es inscrites dans le formulaire de commentaire, mais aussi votre adresse IP et l\u2019agent utilisateur de votre navigateur sont collect\u00e9s pour nous aider \u00e0 la d\u00e9tection des commentaires ind\u00e9sirables.<\/p>\n\n\n\n<p>Une cha\u00eene anonymis\u00e9e cr\u00e9\u00e9e \u00e0 partir de votre adresse de messagerie (\u00e9galement appel\u00e9e hash) peut \u00eatre envoy\u00e9e au service Gravatar pour v\u00e9rifier si vous utilisez ce dernier. Les clauses de confidentialit\u00e9 du service Gravatar sont disponibles ici&nbsp;: https:\/\/automattic.com\/privacy\/. Apr\u00e8s validation de votre commentaire, votre photo de profil sera visible publiquement \u00e0 c\u00f4t\u00e9 de votre commentaire.<\/p>\n\n\n\n<h3>Cookies<\/h3>\n\n\n\n<p>Si vous d\u00e9posez un commentaire sur notre site, il vous sera propos\u00e9 d\u2019enregistrer votre nom, adresse de messagerie et site web dans des cookies. Ceci est propos\u00e9 pour votre confort afin de ne pas avoir \u00e0 resaisir ces informations si vous d\u00e9posez un autre commentaire plus tard. Ces cookies expirent au bout d\u2019un an.<\/p>\n\n\n\n<p>Si vous vous rendez sur la page de connexion, un cookie temporaire sera cr\u00e9\u00e9 afin de d\u00e9terminer si votre navigateur accepte les cookies. Il ne contient pas de donn\u00e9es personnelles et sera supprim\u00e9 automatiquement \u00e0 la fermeture de votre navigateur.<\/p>\n\n\n\n<p>Lorsque vous vous connecterez, nous mettrons en place un certain nombre de cookies pour enregistrer vos informations de connexion et vos pr\u00e9f\u00e9rences d\u2019\u00e9cran. La dur\u00e9e de vie d\u2019un cookie de connexion est de deux jours, celle d\u2019un cookie d\u2019option d\u2019\u00e9cran est d\u2019un an. Si vous cochez \u00ab&nbsp;Se souvenir de moi&nbsp;\u00bb, votre cookie de connexion sera conserv\u00e9 pendant deux semaines. Si vous vous d\u00e9connectez de votre compte, le cookie de connexion sera effac\u00e9.<\/p>\n\n\n\n<p>En modifiant ou en publiant une publication, un cookie suppl\u00e9mentaire sera enregistr\u00e9 dans votre navigateur. Ce cookie ne comprend aucune donn\u00e9e personnelle. Il indique simplement l\u2019ID de la publication que vous venez de modifier. Il expire au bout d\u2019un jour.<\/p>\n\n\n\n<h3>Contenu embarqu\u00e9 depuis d\u2019autres sites<\/h3>\n\n\n\n<p>Les articles de ce site peuvent inclure des contenus int\u00e9gr\u00e9s (par exemple des vid\u00e9os, images, articles\u2026). Le contenu int\u00e9gr\u00e9 depuis d\u2019autres sites se comporte de la m\u00eame mani\u00e8re que si le visiteur se rendait sur cet autre site.<\/p>\n\n\n\n<p>Ces sites web pourraient collecter des donn\u00e9es sur vous, utiliser des cookies, embarquer des outils de suivis tiers, suivre vos interactions avec ces contenus embarqu\u00e9s si vous disposez d\u2019un compte connect\u00e9 sur leur site web.<\/p>\n\n\n\n<h2>Dur\u00e9e de stockage de vos donn\u00e9es<\/h2>\n\n\n\n<p>Si vous laissez un commentaire, le commentaire et ses m\u00e9tadonn\u00e9es sont conserv\u00e9s ind\u00e9finiment. Cela permet de reconna\u00eetre et d&#8217;approuver automatiquement les commentaires suivants au lieu de les laisser dans la file de mod\u00e9ration.<\/p>\n\n\n\n<h2>Les droits que vous avez sur vos donn\u00e9es<\/h2>\n\n\n\n<p>Conform\u00e9ment \u00e0 la r\u00e9glementation europ\u00e9enne en vigueur (RGPD), en tant qu&#8217;utilisateur du site <a rel=\"noreferrer noopener\" href=\"http:\/\/www.tiensmarinecree.com\" target=\"_blank\">www.tiensmarinecree.com<\/a>, si vous avez un compte ou si vous avez laiss\u00e9 des commentaires sur le site, vous pouvez demander \u00e0 recevoir un fichier contenant toutes les donn\u00e9es personnelles que nous poss\u00e9dons \u00e0 votre sujet, incluant celles que vous nous avez fournies. Vous pouvez \u00e9galement demander la rectification ou la suppression des donn\u00e9es personnelles vous concernant. Cela ne prend pas en compte les donn\u00e9es stock\u00e9es \u00e0 des fins administratives, l\u00e9gales ou pour des raisons de s\u00e9curit\u00e9.<\/p>\n\n\n\n<p>Toute demande d&#8217;information, de rectification ou de suppression de vos donn\u00e9es personnelles doit faire l&#8217;objet d&#8217;une demande adress\u00e9e par mail \u00e0 l&#8217;adresse tiensmarinecree[at]mailo.com. L&#8217;utilisateur doit pr\u00e9ciser les donn\u00e9es qu&#8217;il souhaite voir corriger, mettre \u00e0 jour ou supprimer, en s&#8217;identifiant gr\u00e2ce \u00e0 la transmission d&#8217;une pi\u00e8ce d&#8217;identit\u00e9 officielle.  <\/p>\n\n\n\n<p>Les demandes de suppression de donn\u00e9es personnelles restent soumises aux obligations l\u00e9gales qui s&#8217;appliquent \u00e0 Marine Pr\u00e9vot, notamment en mati\u00e8re de conservation ou d&#8217;archivage de documents. <\/p>\n\n\n\n<p>Les utilisateurs du site <a rel=\"noreferrer noopener\" href=\"http:\/\/www.tiensmarinecree.com\" target=\"_blank\">www.tiensmarinecree.com<\/a> peuvent d\u00e9poser une r\u00e9clamation aupr\u00e8s des autorit\u00e9s comp\u00e9tentes de contr\u00f4le, et notamment de la <a href=\"https:\/\/www.cnil.fr\/fr\/plaintes\" data-type=\"URL\" data-id=\"https:\/\/www.cnil.fr\/fr\/plaintes\">CNIL<\/a>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Identification En vertu de l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\u2019\u00c9conomie Num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site internet www.tiensmarinecree.com l\u2019identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi: Propri\u00e9taire : Marine Pr\u00e9vot &#8211; Siret n\u00b0899.001.788.00012 &#8211; 18 rue des aliz\u00e9s, 31750 ESCALQUENS Responsable de la publication : Marine Pr\u00e9vot &#8211; tiensmarinecree[at]mailo.com Webmaster : Marine Pr\u00e9vot &#8211; tiensmarinecree[at]mailo.com D\u00e9l\u00e9gu\u00e9e \u00e0 la protection des donn\u00e9es : Marine Pr\u00e9vot &#8211; tiensmarinecree[at]mailo.com H\u00e9bergeur : OVH &#8211; 2 rue <\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":8,"comment_status":"closed","ping_status":"open","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.tiensmarinecree.com\/index.php\/wp-json\/wp\/v2\/pages\/3"}],"collection":[{"href":"https:\/\/www.tiensmarinecree.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tiensmarinecree.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tiensmarinecree.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tiensmarinecree.com\/index.php\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":6,"href":"https:\/\/www.tiensmarinecree.com\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":558,"href":"https:\/\/www.tiensmarinecree.com\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions\/558"}],"wp:attachment":[{"href":"https:\/\/www.tiensmarinecree.com\/index.php\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}